
{"id":98505,"date":"2026-07-15T19:00:18","date_gmt":"2026-07-15T17:00:18","guid":{"rendered":"https:\/\/www.justineboutique.fr\/wp\/?post_type=product&#038;p=98505"},"modified":"2026-08-25T14:53:12","modified_gmt":"2026-08-25T12:53:12","slug":"ruban-leo-ceinture-et-cheveux","status":"publish","type":"product","link":"https:\/\/www.justineboutique.fr\/wp\/produit\/ruban-leo-ceinture-et-cheveux\/","title":{"rendered":"Foulard ruban l\u00e9o"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<h3><\/h3>\n<p>Le petit accessoire qui change tout !<\/p>\n<p>Le <strong>foulard ruban l\u00e9opard<\/strong> apporte une touche tendance \u00e0 toutes vos tenues.<\/p>\n<p>\u00c0 porter dans les cheveux, autour du cou, en ceinture ou nou\u00e9 sur un sac, il se d\u00e9cline au gr\u00e9 de vos envies pour personnaliser votre look en un clin d&rsquo;\u0153il.<\/p>\n<ul>\n<li>Foulard ruban \u00e0 imprim\u00e9 l\u00e9opard.<\/li>\n<li>Mati\u00e8re satin\u00e9e<\/li>\n<li>Id\u00e9al pour accessoiriser une tenue simple.<\/li>\n<li>Format long, facile \u00e0 nouer.<\/li>\n<li>Convient \u00e0 toutes les saisons.<\/li>\n<\/ul>\n<p>\ud83e\udd0e <strong>Le coup de c\u0153ur de la boutique :<\/strong> un seul accessoire, une multitude de possibilit\u00e9s pour twister vos looks avec une touche sauvage et \u00e9l\u00e9gante.<\/p>\n<p><b>Composition :<\/b><\/p>\n<p>100% viscose<\/p>\n<p><b>Entretien :<\/b><\/p>\n<p>Lavage \u00e0 la main conseill\u00e9<\/p>\n<p>\ud83d\ude9a<b>Livraison rapide et flexible<\/b><\/p>\n<p>Nous mettons tout en \u0153uvre pour vous livrer rapidement et en toute simplicit\u00e9.<\/p>\n<p>Profitez de la livraison offerte en point relais d\u00e8s 80\u20ac d\u2019achat<\/p>\n<p>\ud83d\udd04<b>Retours simplifi\u00e9s \u2013 100% s\u00e9r\u00e9nit\u00e9<\/b><\/p>\n<p>Vous avez\u00a0chang\u00e9 d\u2019avis ? Pas de souci !<\/p>\n<p>Vous disposez de 21 jours apr\u00e8s r\u00e9ception pour retourner un article contre remboursement<\/p>\n","protected":false},"featured_media":98579,"template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_exactmetrics_skip_tracking":false},"product_brand":[],"product_cat":[21,110,124,169,120],"product_tag":[],"class_list":{"0":"post-98505","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-accessoires","7":"product_cat-ceintures","8":"product_cat-echarpe","9":"product_cat-nouveautes","10":"product_cat-voir-tout","11":"pif-has-gallery","13":"first","14":"instock","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-variable"},"_links":{"self":[{"href":"https:\/\/www.justineboutique.fr\/wp\/wp-json\/wp\/v2\/product\/98505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.justineboutique.fr\/wp\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.justineboutique.fr\/wp\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.justineboutique.fr\/wp\/wp-json\/wp\/v2\/media\/98579"}],"wp:attachment":[{"href":"https:\/\/www.justineboutique.fr\/wp\/wp-json\/wp\/v2\/media?parent=98505"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.justineboutique.fr\/wp\/wp-json\/wp\/v2\/product_brand?post=98505"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.justineboutique.fr\/wp\/wp-json\/wp\/v2\/product_cat?post=98505"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.justineboutique.fr\/wp\/wp-json\/wp\/v2\/product_tag?post=98505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}